{"id":8338,"date":"2023-11-27T09:45:26","date_gmt":"2023-11-27T09:45:26","guid":{"rendered":"https:\/\/pernelmedia.com\/?p=8338"},"modified":"2023-11-30T16:26:48","modified_gmt":"2023-11-30T16:26:48","slug":"realscreen-pernel-media-preps-exclusive-access-project-on-major-paleontology-findrealscreen","status":"publish","type":"post","link":"https:\/\/pernelmedia.com\/fr\/realscreen-pernel-media-preps-exclusive-access-project-on-major-paleontology-findrealscreen\/","title":{"rendered":"Realscreen: Pernel Media a s\u00e9curis\u00e9 un acc\u00e8s exclusif \u00e0 une d\u00e9couverte pal\u00e9ontologique majeure"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"8338\" class=\"elementor elementor-8338\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12b3395f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12b3395f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e1cde6e\" data-id=\"7e1cde6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-202fc9a9 elementor-widget elementor-widget-text-editor\" data-id=\"202fc9a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pernel Media a obtenu l'acc\u00e8s exclusif \u00e0  une d\u00e9couverte pal\u00e9ontologique majeure r\u00e9cente, d\u00e9tenant la cl\u00e9 de compr\u00e9hension des origines des mammif\u00e8res, il y a des centaines de millions d'ann\u00e9es.<\/p><p>En 2023, apr\u00e8s quatre d\u00e9cennies de fouilles, des pal\u00e9ontologues sud-africains et fran\u00e7ais ont mis au jour le plus ancien gisement connu de th\u00e9rapsides-les plus anciens anc\u00eatres des mammif\u00e8res- dans le bassin du Karoo, en Afrique du Sud. Les fossiles prouvent que, contrairement aux id\u00e9es re\u00e7ues, des anc\u00eatres de mammif\u00e8res ont r\u00e9gn\u00e9 sur la Terre bien avant l'apparition des dinosaures.\u00a0<\/p><p>Le documentaire de 90 minutes suit les fouilles effectu\u00e9es par les scientifiques en 2024, ainsi que leurs recherches en cours. Des images de synth\u00e8se et des effets visuels de pointe ram\u00e8nent les th\u00e9rapsides \u00e0 la vie ainsi que leur ancien monde. Elles illustrent l'\u00e9volution des mammif\u00e8res pour montrer leur transformation.\u00a0<\/p><p class=\"translation-block\">Le documentaire sera r\u00e9alis\u00e9 par Thomas Cirotteau et co\u00e9crit avec Eric Pincas.<\/p><p><a href=\"https:\/\/realscreen.com\/2023\/11\/24\/pernel-media-preps-exclusive-access-project-on-major-paleontology-find\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-hook=\"linkViewer\">Lire l'article<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pernel Media has secured exclusive access for a new documentary project on a major recent paleontological discovery that is believed to hold the\u00a0key to understanding the origins of mammals some hundreds of millions of years ago. In 2023, after four decades of excavation, South African and French paleontologists unearthed the oldest known deposit of therapsids, [&hellip;]<\/p>\n","protected":false},"author":234053483,"featured_media":8341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[97],"tags":[],"class_list":["post-8338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorised"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/11\/Photo-Karoo-Pernel-Media-23_page-0001.jpg?fit=1638%2C1092&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peJO5x-2au","jetpack-related-posts":[{"id":8512,"url":"https:\/\/pernelmedia.com\/fr\/tbi-pernel-media-explores-rise-of-the-birds-in-new-documentary\/","url_meta":{"origin":8338,"position":0},"title":"TBI: Pernel media explore \"L'Odyss\u00e9e des oiseaux\" dans un nouveau documentaire","author":"ferdinandcolin","date":"25th novembre 2022","format":false,"excerpt":"EXCLUSIVE: ARTE France has ordered a feature doc about the role of Jewish ghettos during the Holocaust.","rel":"","context":"Dans &quot;Uncategorized&quot;","block_context":{"text":"Uncategorized","link":"https:\/\/pernelmedia.com\/fr\/category\/uncategorised\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/12\/Rise-of-the-Birds.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/12\/Rise-of-the-Birds.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/12\/Rise-of-the-Birds.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/12\/Rise-of-the-Birds.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/12\/Rise-of-the-Birds.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11596,"url":"https:\/\/pernelmedia.com\/fr\/tonight-on-nova-gbh-pbs-at-9pm-eastern-mammal-origins\/","url_meta":{"origin":8338,"position":1},"title":"Ce soir sur NOVA (GBH PBS) \u00e0 21h (heure de l\u2019Est), \u00ab Aux origines des mammif\u00e8res \u00bb.","author":"ferdinandcolin","date":"11th f\u00e9vrier 2026","format":false,"excerpt":"NOVA (GBH PBS) will broadcast at 9PM tonight (11\/02) \"Mammals Origins\"! Before the dinosaurs. Before flowers. 260 million years ago, a discreet lineage was already laying the foundations of our existence: the therapsids \u2014 the direct ancestors of mammals\u2026 and therefore of humans. This film was made possible thanks to\u2026","rel":"","context":"Dans &quot;Uncategorized&quot;","block_context":{"text":"Uncategorized","link":"https:\/\/pernelmedia.com\/fr\/category\/uncategorised\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-NOVA.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-NOVA.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-NOVA.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-NOVA.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-NOVA.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3917,"url":"https:\/\/pernelmedia.com\/fr\/satellifacts-pernel-media-production-dune-serie-documentaire-sur-les-mayas-pour-rmc-decouverte\/","url_meta":{"origin":8338,"position":2},"title":"Satellifacts: Pernel Media: production of a documentary series on the Mayas for RMC D\u00e9couverte","author":"pernelmedia","date":"1st avril 2022","format":false,"excerpt":"Pernel Media (Samuel Kissous) a annonc\u00e9 vendredi 1er avril la production de la s\u00e9rie documentaire Les Mayas : du myst\u00e8re des origines \u00e0 la chute (4 x 60'), pour RMC D\u00e9couverte (Altice).","rel":"","context":"Dans &quot;Uncategorized&quot;","block_context":{"text":"Uncategorized","link":"https:\/\/pernelmedia.com\/fr\/category\/uncategorised\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/06\/Rise-and-fall-of-mayas-news-article-pernel-media-e1686149473421.jpg?fit=1200%2C609&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/06\/Rise-and-fall-of-mayas-news-article-pernel-media-e1686149473421.jpg?fit=1200%2C609&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/06\/Rise-and-fall-of-mayas-news-article-pernel-media-e1686149473421.jpg?fit=1200%2C609&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/06\/Rise-and-fall-of-mayas-news-article-pernel-media-e1686149473421.jpg?fit=1200%2C609&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/06\/Rise-and-fall-of-mayas-news-article-pernel-media-e1686149473421.jpg?fit=1200%2C609&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11582,"url":"https:\/\/pernelmedia.com\/fr\/tonight-france-5-presents-presents-mammal-origins\/","url_meta":{"origin":8338,"position":3},"title":"Ce soir sur France 5 'Les origines des mammif\u00e8res - le monde avant les dinosaures'!","author":"ferdinandcolin","date":"15th janvier 2026","format":false,"excerpt":"Tonight, France 5 presents presents \u201cMammal Origins.\u201d Long before the rise of the dinosaurs, and millions of years before the first flowers appeared, a little-known evolutionary branch was already setting a crucial transformation in motion. Two hundred and sixty million years ago, the therapsids paved the way for the emergence\u2026","rel":"","context":"Dans &quot;Uncategorized&quot;","block_context":{"text":"Uncategorized","link":"https:\/\/pernelmedia.com\/fr\/category\/uncategorised\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-FRANCE-5.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-FRANCE-5.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-FRANCE-5.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-FRANCE-5.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2026\/03\/mammif-diff-FRANCE-5.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3858,"url":"https:\/\/pernelmedia.com\/fr\/realscreen-pernel-media-names-mediawan-vet-jean-marc-rouhette-as-companys-first-coo-2\/","url_meta":{"origin":8338,"position":4},"title":"Le documentaire premium de Pernel Media \"Apr\u00e8s la m\u00e9t\u00e9orite\" atterrit sur France T\u00e9l\u00e9visions","author":"pernelmedia","date":"5th novembre 2022","format":false,"excerpt":"La cha\u00eene publique France T\u00e9l\u00e9visions a command\u00e9 After the Asteroid (1\u00d790'), un documentaire haut de gamme r\u00e9alis\u00e9 par la soci\u00e9t\u00e9 de production Pernel Media, soutenue par Vivendi.","rel":"","context":"Dans &quot;Uncategorized&quot;","block_context":{"text":"Uncategorized","link":"https:\/\/pernelmedia.com\/fr\/category\/uncategorised\/"},"img":{"alt_text":"After the asteroid, a Pernel Media documentary series","src":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2021\/08\/After_the_Asteroid-Paleo_impact_asteroid2.jpg?fit=1200%2C692&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2021\/08\/After_the_Asteroid-Paleo_impact_asteroid2.jpg?fit=1200%2C692&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2021\/08\/After_the_Asteroid-Paleo_impact_asteroid2.jpg?fit=1200%2C692&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2021\/08\/After_the_Asteroid-Paleo_impact_asteroid2.jpg?fit=1200%2C692&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2021\/08\/After_the_Asteroid-Paleo_impact_asteroid2.jpg?fit=1200%2C692&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8377,"url":"https:\/\/pernelmedia.com\/fr\/deadline-premium-doc-on-genghis-khan-expedition-in-the-works-with-pernel-media\/","url_meta":{"origin":8338,"position":5},"title":"Deadline : Pernel Media pr\u00e9pare un documentaire sur  Gengis Khan.","author":"ferdinandcolin","date":"28th novembre 2023","format":false,"excerpt":"EXCLUSIVE: ARTE France has ordered a feature doc about the role of Jewish ghettos during the Holocaust.","rel":"","context":"Dans &quot;Uncategorized&quot;","block_context":{"text":"Uncategorized","link":"https:\/\/pernelmedia.com\/fr\/category\/uncategorised\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/11\/Genghis-Kahn-Pernel-Media.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/11\/Genghis-Kahn-Pernel-Media.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/11\/Genghis-Kahn-Pernel-Media.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/11\/Genghis-Kahn-Pernel-Media.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/pernelmedia.com\/wp-content\/uploads\/2023\/11\/Genghis-Kahn-Pernel-Media.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/posts\/8338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/users\/234053483"}],"replies":[{"embeddable":true,"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/comments?post=8338"}],"version-history":[{"count":9,"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/posts\/8338\/revisions"}],"predecessor-version":[{"id":8435,"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/posts\/8338\/revisions\/8435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/media\/8341"}],"wp:attachment":[{"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/media?parent=8338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/categories?post=8338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pernelmedia.com\/fr\/wp-json\/wp\/v2\/tags?post=8338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}